{"id":170,"date":"2023-03-04T14:14:00","date_gmt":"2023-03-04T13:14:00","guid":{"rendered":"https:\/\/www.metodcrea.org\/?page_id=170"},"modified":"2023-03-04T14:14:00","modified_gmt":"2023-03-04T13:14:00","slug":"contact","status":"publish","type":"page","link":"https:\/\/www.metodcrea.org\/index.php\/contact\/","title":{"rendered":"Contact"},"content":{"rendered":"<div class=\"wpforms-container wpforms-container-full\" id=\"wpforms-167\"><form id=\"wpforms-form-167\" class=\"wpforms-validate wpforms-form wpforms-ajax-form\" data-formid=\"167\" method=\"post\" enctype=\"multipart\/form-data\" action=\"\/index.php\/wp-json\/wp\/v2\/pages\/170\" data-token=\"89b53469acd4a230ea766e4035b9c71f\"><noscript class=\"wpforms-error-noscript\">Veuillez activer JavaScript dans votre navigateur pour remplir ce formulaire.<\/noscript><div class=\"wpforms-field-container\"><div id=\"wpforms-167-field_0-container\" class=\"wpforms-field wpforms-field-name\" data-field-id=\"0\"><label class=\"wpforms-field-label\" for=\"wpforms-167-field_0\">Nom <span class=\"wpforms-required-label\">*<\/span><\/label><div class=\"wpforms-field-row wpforms-field-medium\"><div class=\"wpforms-field-row-block wpforms-first wpforms-one-half\"><input type=\"text\" id=\"wpforms-167-field_0\" class=\"wpforms-field-name-first wpforms-field-required\" name=\"wpforms[fields][0][first]\" required><label for=\"wpforms-167-field_0\" class=\"wpforms-field-sublabel after \">Pr\u00e9nom<\/label><\/div><div class=\"wpforms-field-row-block wpforms-one-half\"><input type=\"text\" id=\"wpforms-167-field_0-last\" class=\"wpforms-field-name-last wpforms-field-required\" name=\"wpforms[fields][0][last]\" required><label for=\"wpforms-167-field_0-last\" class=\"wpforms-field-sublabel after \">Nom<\/label><\/div><\/div><\/div><div id=\"wpforms-167-field_1-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"1\"><label class=\"wpforms-field-label\" for=\"wpforms-167-field_1\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-167-field_1\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][1]\" required><\/div><div id=\"wpforms-167-field_2-container\" class=\"wpforms-field wpforms-field-textarea\" data-field-id=\"2\"><label class=\"wpforms-field-label\" for=\"wpforms-167-field_2\">Commentaire ou message<\/label><textarea id=\"wpforms-167-field_2\" class=\"wpforms-field-medium\" name=\"wpforms[fields][2]\" ><\/textarea><\/div><div id=\"wpforms-167-field_6-container\" class=\"wpforms-field wpforms-field-email\" data-field-id=\"6\"><label class=\"wpforms-field-label\" for=\"wpforms-167-field_6\">E-mail <span class=\"wpforms-required-label\">*<\/span><\/label><input type=\"email\" id=\"wpforms-167-field_6\" class=\"wpforms-field-medium wpforms-field-required\" name=\"wpforms[fields][6]\" required><\/div><\/div><div class=\"wpforms-submit-container\"><input type=\"hidden\" name=\"wpforms[id]\" value=\"167\"><input type=\"hidden\" name=\"wpforms[author]\" value=\"1\"><button type=\"submit\" name=\"wpforms[submit]\" id=\"wpforms-submit-167\" class=\"wpforms-submit\" data-alt-text=\"Envoi...\" data-submit-text=\"Envoyer\" aria-live=\"assertive\" value=\"wpforms-submit\">Envoyer<\/button><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.metodcrea.org\/wp-content\/plugins\/wpforms-lite\/assets\/images\/submit-spin.svg\" class=\"wpforms-submit-spinner\" style=\"display: none;\" width=\"26\" height=\"26\" alt=\"Chargement en cours\"><\/div><\/form><\/div>  <!-- .wpforms-container -->","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-170","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/pages\/170","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/comments?post=170"}],"version-history":[{"count":1,"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/pages\/170\/revisions"}],"predecessor-version":[{"id":171,"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/pages\/170\/revisions\/171"}],"wp:attachment":[{"href":"https:\/\/www.metodcrea.org\/index.php\/wp-json\/wp\/v2\/media?parent=170"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}